{"id":37,"count":2,"description":"Digital map","link":"https:\/\/nextrail.com\/en\/category\/digital-map-en\/","name":"Digital map","slug":"digital-map-en","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/nextrail.com\/en\/wp-json\/wp\/v2\/categories\/37","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nextrail.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/nextrail.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/nextrail.com\/en\/wp-json\/wp\/v2\/posts?categories=37"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}